{"id":19,"count":1,"description":"","link":"https:\/\/www.electrichellos.com\/blog\/tag\/dating-safty\/","name":"dating safty","slug":"dating-safty","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.electrichellos.com\/blog\/wp-json\/wp\/v2\/tags\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.electrichellos.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.electrichellos.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.electrichellos.com\/blog\/wp-json\/wp\/v2\/posts?tags=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}