{"id":42,"count":1,"description":"","link":"https:\/\/www.electrichellos.com\/blog\/tag\/she-wont-call-back\/","name":"she wont call back","slug":"she-wont-call-back","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.electrichellos.com\/blog\/wp-json\/wp\/v2\/tags\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.electrichellos.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.electrichellos.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.electrichellos.com\/blog\/wp-json\/wp\/v2\/posts?tags=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}